{"id":5186,"date":"2023-09-26T17:10:06","date_gmt":"2023-09-26T15:10:06","guid":{"rendered":"https:\/\/ecc-netitalia.it\/?p=5186"},"modified":"2023-10-11T17:35:47","modified_gmt":"2023-10-11T15:35:47","slug":"pacchetti-turistici-il-giudice-puo-informare-il-viaggiatore-sullesistenza-del-diritto-alla-risoluzione-del-contratto-al-verificarsi-di-circostanze-straordinarie","status":"publish","type":"post","link":"https:\/\/ecc-netitalia.it\/it\/news\/pacchetti-turistici-il-giudice-puo-informare-il-viaggiatore-sullesistenza-del-diritto-alla-risoluzione-del-contratto-al-verificarsi-di-circostanze-straordinarie\/","title":{"rendered":"Pacchetti turistici: il giudice pu\u00f2 informare il viaggiatore sull\u2019esistenza del diritto alla risoluzione del contratto al verificarsi di circostanze straordinarie"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00c8 il principio stabilito dalla\u00a0<strong>Corte di Giustizia dell\u2019UE<\/strong>\u00a0in seguito alla domanda pregiudiziale di un giudice spagnolo (causa C-83\/22) protesa all\u2019interpretazione delle norme comunitarie in materia di\u00a0<a href=\"https:\/\/ecc-netitalia.it\/it\/pacchetti-turistici\/\" target=\"_blank\" rel=\"noopener\"><strong>pacchetti turistici<\/strong><\/a>\u00a0e, in particolare, sulla possibilit\u00e0 per il giudice di dichiarare d\u2019ufficio la risoluzione del contratto.<\/p>\n<p style=\"text-align: justify;\">Nel\u00a0<strong>caso di specie<\/strong>, un consumatore aveva acquistato tramite l&#8217;organizzatore di viaggi\u00a0<strong>Tuk Tuk Travel<\/strong>\u00a0un pacchetto turistico con destinazione Vietnam e Cambogia nell\u2019ottobre 2019, pagando quasi la met\u00e0 del prezzo totale dell\u2019intero viaggio. La partenza era prevista per il giorno 8 marzo 2020, mentre il ritorno era previsto per il 24 dello stesso mese. Il 12 febbraio 2020, per\u00f2, il consumatore ha informato l\u2019organizzatore della sua decisione di risolvere il contratto a causa della diffusione del Covid-19 in Asia, chiedendo il rimborso del corrispettivo versato al netto delle spese di gestione sostenute dall\u2019organizzatore. Quest\u2019ultimo, tuttavia, riteneva di dover restituire solo una minima parte dell\u2019importo versato dal viaggiatore in quanto gli erano dovute le spese di annullamento contrattualmente previste.<\/p>\n<p style=\"text-align: justify;\">La Corte UE ha\u00a0<strong>precisato<\/strong>, innanzitutto, che la direttiva sui pacchetti turistici impone all&#8217;organizzatore di viaggi di fornire al viaggiatore una serie di informazioni, tra cui l\u2019informazione relativa al suo diritto di risoluzione del pacchetto turistico, qualifica dall\u2019avvocato generale come un diritto fondamentale del viaggiatore. Trattandosi di un diritto riconosciuto dalla Direttiva, la relativa tutela legittima il giudice nazionale a rilevarne d\u2019ufficio la violazione, in particolare quando il viaggiatore non fa valere il suo diritto perch\u00e9 ne ignora l\u2019esistenza. Tale esame d\u2019ufficio pu\u00f2 aver luogo ogni qual volta il diritto di risoluzione \u00e8 connesso all\u2019oggetto della controversia, il giudice nazionale possiede tutti gli elementi di diritto e di fatto necessari per valutare se tale diritto di risoluzione possa essere invocato dal viaggiatore interessato e possa ritenersi verosimile che il viaggiatore non si sia appellato a tale suo diritto, bench\u00e9 applicabile, perch\u00e9 ne ignorasse l\u2019esistenza.<\/p>\n<p style=\"text-align: justify;\">Nella disamina della questione sottoposta alla Corte, la stessa rileva che il contratto da cui aveva tratto origine la controversia forniva informazioni sulla possibilit\u00e0 di risoluzione del pacchetto turistico prima della data di partenza avverso il pagamento di spese di annullamento, ma nulla riferiva in merito alla possibilit\u00e0 del viaggiatore di risolvere il contratto senza incorrere in spesa alcuna per il verificarsi di circostanze inevitabili e straordinarie nel luogo di destinazione o nelle immediate vicinanze, come previsto dalla direttiva sui pacchetti turistici. Contestualmente, la Corte precisa che il giudice nazionale chiamato a valutare la ricorrenza delle circostanze inevitabili e straordinarie pu\u00f2 basarsi sulla nozione che delle stesse \u00e8 stata fornita in occasione della sentenza dell\u20198 giugno 2023 (C-407\/21) pu\u00f2 comprendere lo scoppio di una crisi sanitaria mondiale.<\/p>\n<p style=\"text-align: justify;\">La Corte, in sostanza, ha\u00a0<strong>affermato<\/strong>\u00a0il principio secondo cui se non \u00e8 possibile escludere che il consumatore abbia ignorato l\u2019esistenza del suo diritto di risoluzione poich\u00e9 non informato al riguardo dall\u2019organizzatore, il giudice nazionale, non pu\u00f2 risolvere dichiarare d\u2019ufficio la risoluzione del contratto, ma pu\u00f2 fornire tale informazione e concedere al viaggiatore la possibilit\u00e0 di far valere questo suo diritto nel procedimento \u00a0giurisdizionale in corso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 il principio stabilito dalla\u00a0Corte di Giustizia dell\u2019UE\u00a0in seguito alla domanda pregiudiziale di un giudice spagnolo (causa C-83\/22) protesa all\u2019interpretazione delle norme comunitarie in materia di\u00a0pacchetti turistici\u00a0e, in particolare, sulla possibilit\u00e0 per il giudice di dichiarare d\u2019ufficio la risoluzione del contratto. Nel\u00a0caso di specie, un consumatore aveva acquistato tramite l&#8217;organizzatore di viaggi\u00a0Tuk Tuk Travel\u00a0un pacchetto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[250],"class_list":["post-5186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-pacchetti-turistici"],"_links":{"self":[{"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/posts\/5186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/comments?post=5186"}],"version-history":[{"count":3,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/posts\/5186\/revisions"}],"predecessor-version":[{"id":5191,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/posts\/5186\/revisions\/5191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/media\/5187"}],"wp:attachment":[{"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/media?parent=5186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/categories?post=5186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ecc-netitalia.it\/it\/wp-json\/wp\/v2\/tags?post=5186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}